{"id":31426,"date":"2024-10-29T08:31:18","date_gmt":"2024-10-29T12:31:18","guid":{"rendered":"https:\/\/flexfunds.com\/fund-world-news\/flexportfolio-innovation-asset-management-global\/"},"modified":"2026-06-30T08:24:36","modified_gmt":"2026-06-30T12:24:36","slug":"flexportfolio-innovacion-gestion-de-activos-global","status":"publish","type":"post","link":"https:\/\/flexfunds.com\/es\/solutions\/flexportfolio-innovacion-gestion-de-activos-global\/","title":{"rendered":"FlexPortfolio: innovaci\u00f3n en la gesti\u00f3n de activos para un mercado global"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>En este art\u00edculo, se detallan cu\u00e1les son los beneficios del FlexPortfolio de FlexFunds frente a alternativas como los actively managed certificates (AMC).<\/li>\n\n\n\n<li>La informaci\u00f3n est\u00e1 dirigida, prioritariamente, a gestores de activos y asesores que est\u00e9n buscando soluciones para distribuir m\u00e1s f\u00e1cilmente y a un menor costo sus estrategias de inversi\u00f3n.<\/li>\n\n\n\n<li>En FlexFunds, brindamos un programa de securitizaci\u00f3n de activos para emitir productos listados en bolsa (ETP), en menos de la mitad del tiempo y coste que otras alternativas existentes en el mercado. Para m\u00e1s informaci\u00f3n, no dude en <a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDUwNywidG9nZ2xlIjpmYWxzZX0%3D\">ponerse en contacto con nuestro grupo de expertos.&nbsp;<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La industria de la gesti\u00f3n de activos a nivel mundial est\u00e1 creciendo a pasos agigantados<\/strong>. De hecho, seg\u00fan un estudio de PwC, se estima que los activos bajo gesti\u00f3n (AuM, por su sigla en ingl\u00e9s) aumentar\u00e1n a un ritmo del 6,2% anual hasta los <strong>USD 145,4 billones en 2025<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y gran parte de esta expansi\u00f3n podr\u00eda estar vinculada a las <strong>nuevas e innovadoras soluciones de distribuci\u00f3n de inversiones<\/strong>, como el <strong>FlexPortfolio<\/strong> de FlexFunds, que ofrecen varios beneficios frente a los actively managed certificates (AMC).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM0NDkxIiwidG9nZ2xlIjpmYWxzZX0%3D\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1120\" height=\"200\" src=\"https:\/\/flexfunds.com\/wp-content\/uploads\/2025\/09\/Banner-1_ES_desktop-V5.png\" alt=\"\" class=\"wp-image-34479\" srcset=\"https:\/\/flexfunds.com\/wp-content\/uploads\/2025\/09\/Banner-1_ES_desktop-V5.png 1120w, https:\/\/flexfunds.com\/wp-content\/uploads\/2025\/09\/Banner-1_ES_desktop-V5-300x54.png 300w, https:\/\/flexfunds.com\/wp-content\/uploads\/2025\/09\/Banner-1_ES_desktop-V5-1024x183.png 1024w, https:\/\/flexfunds.com\/wp-content\/uploads\/2025\/09\/Banner-1_ES_desktop-V5-768x137.png 768w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es FlexPortfolio?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Puntualmente, el FlexPortfolio es un veh\u00edculo de inversi\u00f3n que permite securitizar una gran cantidad de <a href=\"https:\/\/flexfunds.com\/es\/solutions\/por-que-los-gestores-de-activos-deberian-considerar-los-etps-dentro-de-su-oferta-de-portafolios-2\/\">activos listados<\/a>. Ofrece soluciones llave en mano simplificadas a los asesores de inversi\u00f3n para que puedan crear su propio veh\u00edculo de inversi\u00f3n (ETP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s del FlexPortfolio, se pueden <strong>crear productos listados en bolsa (ETP) sobre activos l\u00edquidos <\/strong>como acciones, bonos, opciones, futuros, divisas y fondos cotizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, el <a href=\"https:\/\/flexfunds.com\/es\/flexportfolio\/\">FlexPortfolio<\/a> se compone de cuatro soluciones llamadas <strong>\u201cFlex\u201d<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>FlexPortfolio<\/strong>: crea ETP no regulados, permite titulizar una estrategia con activos listados en una cuenta de custodia del Bank of New York o Interactive Brokers.<\/li>\n\n\n\n<li><strong>Flex Open Portfolio<\/strong>: tituliza una cartera de activos listados en una cuenta custodio de preferencia.<\/li>\n\n\n\n<li><strong>FlexRegulated Portfolio<\/strong>: se trata de un veh\u00edculo de inversi\u00f3n regulado por el Banco Central de Irlanda que securitiza activos listados dentro de una cuenta de Interactive Brokers dirigido a inversores institucionales y minoristas. <\/li>\n\n\n\n<li><strong>Flex Dual Portfolio<\/strong>: Tituliza un portafolio de activos listados dentro de una cuenta de Interactive Brokers y de Bank of New York.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Beneficios del FlexPortfolio frente a los AMC<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las soluciones del FlexPortfolio ofrecen <a href=\"https:\/\/flexfunds.com\/es\/flexfunds\/por-que-el-flexportfolio-es-una-alternativa-que-puede-ser-mas-eficiente-que-los-certificados-administrados-activamente-amcs\/\">m\u00faltiples beneficios en comparaci\u00f3n con los actively managed certificates<\/a>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Facilidad de distribuci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, gracias a los Flex, <strong>los inversores pueden acceder a estrategias de inversi\u00f3n completas sobre activos l\u00edquidos directamente desde su cuenta de corretaje<\/strong>, ya que, al ser \u201ceuroclearables\u201d, se pueden <a href=\"https:\/\/flexfunds.com\/es\/trends-numbers\/como-la-tecnologia-transforma-la-industria-financiera\/\">distribuir a nivel global<\/a>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">En cambio, en el caso de los AMC, su liquidez suele ser menor porque, en algunos casos, sus participaciones no se pueden comprar y vender tan f\u00e1cilmente.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Flexibilidad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, el FlexPortfolio de FlexFunds permite <strong>titulizar m\u00faltiples activos l\u00edquidos<\/strong>. En este grupo, se destacan acciones de todo tipo, bonos p\u00fablicos o privados, muchos derivados financieros, <a href=\"https:\/\/flexfunds.com\/es\/flexfunds\/ventajas-riesgos-fondos-cotizados-etf-bolsa\/\">fondos cotizados en bolsa (ETF)<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Capacidad de gesti\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, pr\u00e1cticamente no hay restricciones en cuanto al rebalanceo o comercializaci\u00f3n de la cuenta subyacente del FlexPortfolio. En otras palabras, <strong>el gestor de activos puede ejecutar todas las operaciones directamente en la cuenta de corretaje<\/strong> sin que sea necesaria la participaci\u00f3n de terceros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Emisi\u00f3n segura<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, otro de los beneficios de los Flex es su alta seguridad de emisi\u00f3n. La estrategia est\u00e1 respaldada por los activos subyacentes l\u00edquidos y <strong>es totalmente independiente de las actividades del promotor<\/strong>. Sin embargo, en los AMC, el emisor puede nombrar a un tercero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Costes competitivos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, <strong>el FlexPortfolio puede llegar a no tener coste de set up ni de mantenimiento<\/strong>, lo que lo hace un <a href=\"https:\/\/flexfunds.com\/es\/solutions\/mejores-vehiculos-de-inversion-2024\/\">veh\u00edculo de inversi\u00f3n<\/a> costo-eficiente. Por su parte, los actively managed certificates, los costes suelen ser mayores.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Rapidez de lanzamiento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, <strong>un Flex tarda entre 8 y 12 semanas en ser lanzado al mercado<\/strong>, dependiendo de la soluci\u00f3n en particular escogida. En comparaci\u00f3n, otros veh\u00edculos de inversi\u00f3n pueden requerir un tiempo de lanzamiento superior a los seis meses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo securitizar activos l\u00edquidos con FlexFunds<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para acceder al FlexPortfolio y sus m\u00faltiples beneficios frente a los AMC, s\u00f3lo hay que <a href=\"https:\/\/flexfunds.com\/es\/solutions\/paso-a-paso-como-es-el-proceso-de-titularizacion-de-activos\/\">seguir cinco pasos<\/a>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paso 1: Estudio personalizado y dise\u00f1o del ETP<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a que el proceso de titulizaci\u00f3n puede darse sobre una gran cantidad de activos de diferente naturaleza (tanto listados en mercados secundarios como privados), es necesario analizar cada caso y ofrecer una soluci\u00f3n dise\u00f1ada a medida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paso 2: Due diligence y firma del engagement letter<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez definida la estructura del producto, el comit\u00e9 de riesgo procede al estudio y evaluaci\u00f3n del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, se procede a la firma del engagement letter, el contrato donde se especifican los t\u00e9rminos y condiciones del servicio, as\u00ed como el alcance de las funciones que llevar\u00e1 a cabo FlexFunds.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paso 3: Estructuraci\u00f3n del ETP y revisi\u00f3n de documentos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario que durante la estructura de la titulizaci\u00f3n se trabaje estrechamente con el cliente para el correcto desarrollo de la documentaci\u00f3n necesaria que dar\u00e1 forma al ETP. Es en este paso cuando se realiza el onboarding del portfolio manager.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paso 4: emisi\u00f3n y listado del ETP<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La titulizaci\u00f3n de activos ya es una realidad. En este momento, su estrategia de inversi\u00f3n est\u00e1 empaquetada en un ETP. Ahora es necesario proceder a su listado y generar un ISIN\/CUSIP que facilite su distribuci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Emisor de los t\u00edtulos es una sociedad de prop\u00f3sito especial irlandesa (SPV) creada para tales efectos. La emisi\u00f3n se encuentra respaldada por la propia estrategia de inversi\u00f3n, que act\u00faa como colateral.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Paso 5. El ETP est\u00e1 listo para su negociaci\u00f3n a trav\u00e9s de Euroclear<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de titulizaci\u00f3n de activos acaba con la emisi\u00f3n y listado del ETP. Es decir, cuando se encuentra listo para su distribuci\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Recuerde que <strong>nuestro gran diferencial se basa en coordinar un programa de titulizaci\u00f3n de activos de manera r\u00e1pida y eficiente<\/strong>, haci\u00e9ndonos cargo de supervisar todas las fases del proceso de principio a fin para otorgar una soluci\u00f3n llave en mano para nuestros clientes.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para conocer m\u00e1s acerca de <a href=\"https:\/\/flexfunds.com\/es\/solutions\/securitization-how-to-convert-assets-into-bankable-assets-through-an-etp-2\/\">nuestras soluciones de securitizaci\u00f3n<\/a>, no dude en visitar nuestra secci\u00f3n <a href=\"https:\/\/flexfunds.com\/es\/flexportfolio\/\">FlexPortfolio<\/a> y concretar una<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDUwNywidG9nZ2xlIjpmYWxzZX0%3D\"> reuni\u00f3n con nuestros expertos.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las soluciones del FlexPortfolio de FlexFunds brindan m\u00faltiples beneficios frente a los actively managed certificate (AMC), como su menor costo y mayor flexibilidad.<\/p>\n","protected":false},"author":13,"featured_media":31470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[118],"tags":[],"class_list":["post-31426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions"],"acf":[],"_links":{"self":[{"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/posts\/31426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/comments?post=31426"}],"version-history":[{"count":1,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/posts\/31426\/revisions"}],"predecessor-version":[{"id":40091,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/posts\/31426\/revisions\/40091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/media\/31470"}],"wp:attachment":[{"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/media?parent=31426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/categories?post=31426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flexfunds.com\/es\/wp-json\/wp\/v2\/tags?post=31426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}